{"id":840,"count":1,"description":"","link":"https:\/\/jehmlich-orgelbau.de\/en\/tag\/56-register-en\/","name":"56 Register","slug":"56-register-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>56 Register Archives | Jehmlich Orgelbau Dresden<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"56 Register Archives | Jehmlich Orgelbau Dresden\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jehmlich-orgelbau.de\/en\/tag\/56-register-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Jehmlich Orgelbau Dresden\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/en\\\/tag\\\/56-register-en\\\/\",\"url\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/en\\\/tag\\\/56-register-en\\\/\",\"name\":\"56 Register Archives | Jehmlich Orgelbau Dresden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/en\\\/tag\\\/56-register-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/en\\\/tag\\\/56-register-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"56 Register\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/en\\\/\",\"name\":\"Jehmlich Orgelbau Dresden\",\"description\":\"Orgelbau seit 1808\",\"publisher\":{\"@id\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/en\\\/#organization\",\"name\":\"Jehmlich Orgelbau Dresden GmbH\",\"url\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Orgelbau-Jehmlich-Dresden-Logo.png\",\"contentUrl\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Orgelbau-Jehmlich-Dresden-Logo.png\",\"width\":275,\"height\":104,\"caption\":\"Jehmlich Orgelbau Dresden GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/jehmlich-orgelbau.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"56 Register Archives | Jehmlich Orgelbau Dresden","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"56 Register Archives | Jehmlich Orgelbau Dresden","og_url":"https:\/\/jehmlich-orgelbau.de\/en\/tag\/56-register-en\/","og_site_name":"Jehmlich Orgelbau Dresden","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jehmlich-orgelbau.de\/en\/tag\/56-register-en\/","url":"https:\/\/jehmlich-orgelbau.de\/en\/tag\/56-register-en\/","name":"56 Register Archives | Jehmlich Orgelbau Dresden","isPartOf":{"@id":"https:\/\/jehmlich-orgelbau.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/jehmlich-orgelbau.de\/en\/tag\/56-register-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/jehmlich-orgelbau.de\/en\/tag\/56-register-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jehmlich-orgelbau.de\/en\/"},{"@type":"ListItem","position":2,"name":"56 Register"}]},{"@type":"WebSite","@id":"https:\/\/jehmlich-orgelbau.de\/en\/#website","url":"https:\/\/jehmlich-orgelbau.de\/en\/","name":"Jehmlich Orgelbau Dresden","description":"Orgelbau seit 1808","publisher":{"@id":"https:\/\/jehmlich-orgelbau.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jehmlich-orgelbau.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/jehmlich-orgelbau.de\/en\/#organization","name":"Jehmlich Orgelbau Dresden GmbH","url":"https:\/\/jehmlich-orgelbau.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jehmlich-orgelbau.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/jehmlich-orgelbau.de\/wp-content\/uploads\/2019\/04\/Orgelbau-Jehmlich-Dresden-Logo.png","contentUrl":"https:\/\/jehmlich-orgelbau.de\/wp-content\/uploads\/2019\/04\/Orgelbau-Jehmlich-Dresden-Logo.png","width":275,"height":104,"caption":"Jehmlich Orgelbau Dresden GmbH"},"image":{"@id":"https:\/\/jehmlich-orgelbau.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jehmlich-orgelbau.de\/en\/wp-json\/wp\/v2\/tags\/840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jehmlich-orgelbau.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jehmlich-orgelbau.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jehmlich-orgelbau.de\/en\/wp-json\/wp\/v2\/posts?tags=840"},{"href":"https:\/\/jehmlich-orgelbau.de\/en\/wp-json\/wp\/v2\/orgelprojekte?tags=840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}